{"id":25862,"date":"2025-03-19T16:09:30","date_gmt":"2025-03-19T15:09:30","guid":{"rendered":"https:\/\/www.topconsult.it\/?p=25862"},"modified":"2025-03-20T18:15:10","modified_gmt":"2025-03-20T17:15:10","slug":"fatturazione-elettronica-europea-cose-e-perche-se-ne-parla","status":"publish","type":"post","link":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla","title":{"rendered":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25862\" class=\"elementor elementor-25862\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d7bdd07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d7bdd07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-309a51e8\" data-id=\"309a51e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-314c8035 elementor-widget elementor-widget-text-editor\" data-id=\"314c8035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partire dall\u2019inizio di gennaio del 2028 (anche se gi\u00e0 si parla di rimandare al 2030) entrer\u00e0 in vigore la <strong>fatturazione elettronica europea<\/strong>. Secondo quanto riportato dall\u2019Agenzia delle Entrate nell\u2019intero Continente si far\u00e0 riferimento a un unico <em>\u201csistema predefinito per l\u2019emissione di fatture, vi sar\u00e0 obbligo di fatturazione elettronica delle operazioni intraUE con un formato standard europeo e la possibilit\u00e0 di utilizzare lo standard europeo o altri standard nazionali nel caso di obbligo di fatturazione elettronica delle operazioni nazionali disposto dal singolo Stato membro\u201d<\/em>.<\/p><p>La fatturazione elettronica europea si inserisce in un pi\u00f9 ampio insieme di iniziative chiamato <strong>VAT in the Digital Age<\/strong>, la proposta studiata per rinnovare l\u2019approccio all\u2019IVA negli scambi transfrontalieri e per semplificare le procedure a essi inerenti. In tale contesto, l\u2019adozione della <a href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/fattura-elettronica-passaggi-chiave-per-lemissione-e-invio-efficiente\">fattura elettronica<\/a> \u00e8 fissata come il metodo per emettere documenti fiscali in formato digitale entro i confini dell\u2019Unione.<\/p><hr \/><h2>Cos\u2019\u00e8 la fatturazione elettronica europea e a cosa serve<\/h2><p>Stabilire il processo di fatturazione elettronica europea \u00e8 una delle azioni della Commissione Europea che mira alla <strong>creazione del Mercato Unico Digitale<\/strong>, per facilitare la collaborazione tra partner commerciali che operano in stati diversi. Oltre a questo, naturalmente, un simile impegno si spiega anche con la <strong>volont\u00e0 di armonizzare e modernizzare le metodologie amministrative<\/strong> e, infine, <strong>ostacolare l\u2019evasione fiscale<\/strong>.<\/p><p>L\u2019Italia \u00e8 tra i pionieri nell\u2019adozione del processo di <a href=\"https:\/\/www.topconsult.it\/it\/fatturazione-elettronica\">fatturazione elettronica<\/a> avendolo reso obbligatorio ormai da tempo, dal 2019. Gli altri Paesi si stanno organizzando, tra questi, per esempio, la Germania sta pianificando la <a href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/digitalizzazione-documenti-cartacei-9-step-per-una-trasformazione-immediata\">digitalizzazione dei documenti<\/a> fiscali tra il 2027 e il 2028.<br \/>La questione \u00e8 ovviamente molto importante perch\u00e9 offre interessanti opportunit\u00e0 dal punto di vista commerciale ma, d\u2019altra parte, <strong>fa discutere a proposito dei diversi approcci<\/strong>, oltre che in merito tipologia di piattaforme centralizzate e cos\u00ec via.<\/p><p>Per quanto concerne le opportunit\u00e0 riconducibili alla digitalizzazione, in primo luogo si deve fare riferimento alla <strong>trasparenza e alla completa tracciabilit\u00e0 dei flussi finanziari<\/strong>. Le autorit\u00e0 fiscali possono pi\u00f9 facilmente tenere sotto controllo le operazioni, minimizzando i rischi di irregolarit\u00e0 e innalzando il livello complessivo di compliance alle normative. Del resto, anche i consumatori finali e i partner commerciali si aspettano sempre pi\u00f9 <strong>chiarezza gestionale da parte delle aziende<\/strong>.<\/p><p>Inoltre, la standardizzazione dei processi avr\u00e0 il prezioso effetto di <strong>abbassare le barriere commerciali<\/strong> e innalzare il grado di competitivit\u00e0 dell\u2019intero sistema. Al contempo, le aziende possono beneficiare del fatto di fruire dei vantaggi economici riconducibili alla <a href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/dematerializzazione-e-digitalizzazione-tecniche-e-metodi-per-sostituire-i-documenti-cartacei\">dematerializzazione<\/a>, dai risparmi alla possibilit\u00e0 di <strong>impostare nuovi modelli di lavoro<\/strong> e innovativi servizi.<\/p><p><a title=\"Top Consult guida Servotecnica alla piena digitalizzazione\" href=\"\/it\/blog\/news\/top-consult-guida-servotecnica-alla-piena-digitalizzazione\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive alignnone\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/banner_case_study_servotecnica_761x200_v1-1.gif\" alt=\"Scopri come diventare un'azienda digitale - Case study Servotecnica\" width=\"761\" height=\"200\" title=\"Scopri come diventare un'azienda digitale - Case study Servotecnica\" \/><\/a><\/p><hr \/><h2>Fatturazione elettronica europea, gli standard e il ruolo di Peppol<\/h2><p>Nel quadro della direttiva <strong>2014\/55\/UE<\/strong> gi\u00e0 si introduceva l\u2019idea di fattura elettronica dell\u2019Unione Europea che favorisse uno scambio in un formato digitale strutturato, inizialmente in riferimento agli appalti pubblici e poi sempre pi\u00f9 in generale. A tal proposito sono stati descritti gli standard europei che sono l\u2019<strong>UBL 2.1<\/strong> e la <strong>CII<\/strong> (Cross Industry Invoice).<br \/>D\u2019altra parte, <strong>Peppol<\/strong> (Pan-European Public Procurement OnLine) \u00e8 il fattore chiave per implementare la fatturazione elettronica europea. Si tratta della rete che permette lo scambio delle e-fatture, la piattaforma a cui tanti Paesi stanno ricorrendo sfruttando lo <strong>standard PINT<\/strong> (Pan-European Public Procurement Online Interoperability) strettamente correlato allo standard europeo <strong>EN 16931<\/strong>, il formato semantico comune per le fatture elettroniche in Europa.<br \/>Dal punto di vista pratico, <a href=\"https:\/\/www.topconsult.it\/it\/peppol\">Peppol<\/a> funziona secondo principi simili a quelli dell\u2019italiano <strong>SDI \u2013 Sistema di interscambio<\/strong>, garantendo l\u2019indirizzo del destinatario e verificando la disponibilit\u00e0 di quest\u2019ultimo a ricevere un documento fiscale, mediante Access Point Provider forniti da enti certificati da AgID (Certified Peppol Providers).<\/p><hr \/><h3>Cosa fare per implementare la fatturazione elettronica europea<\/h3><p>Per quanto riguarda le aziende italiane, gi\u00e0 abituate alla realizzazione di <a href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/fattura-elettronica-aggiornamento-normativa-vademecum-per-il-futuro\">fatture digitali<\/a>, non si vivranno particolari stravolgimenti dal punto di vista operativo.<\/p><p>Ci\u00f2 che occorrer\u00e0 fare \u00e8 <strong>far evolvere e potenziare le infrastrutture digitali<\/strong> in modo da supportare la fatturazione elettronica europea e adottare i requisiti internazionali, oltre che investire in formazione e supporto necessari per compiere la transizione.<\/p><p>La tecnologia agevola quel che la legislazione sta spingendo, ossia la possibilit\u00e0 di avere una visione unitaria dei <a href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-passiva-e-attiva-come-si-gestisce-le-differenze\">processi di fatturazione<\/a> siano essi svolti in Italia sia che si abbiano rapporti con l\u2019estero. Ci\u00f2 significa, pi\u00f9 nello specifico, che attraverso gli applicativi pi\u00f9 avanzati si avr\u00e0 la possibilit\u00e0 di fruire di un\u2019<strong>unica piattaforma<\/strong> per gestire i diversi documenti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c0b78c8 box-call-to-action e-flex e-con-boxed e-con e-parent\" data-id=\"c0b78c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-90b0a45 e-con-full e-flex e-con e-child\" data-id=\"90b0a45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84fd51a elementor-widget elementor-widget-text-editor\" data-id=\"84fd51a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><div>MIGLIORA LA GESTIONE DEI DOCUMENTI AZIENDALI<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92e7c70 elementor-widget elementor-widget-text-editor\" data-id=\"92e7c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per sapere come gestire completamente il ciclo di fatturazione, scarica la tua copia gratuita della guida: \u201c<strong>Tutti i passi necessari per fare la fattura elettronica<\/strong>\u201c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ded96f9 elementor-widget elementor-widget-html\" data-id=\"ded96f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-f765f6a0-a051-4753-9955-c30a57f98b73\"><span class=\"hs-cta-node hs-cta-f765f6a0-a051-4753-9955-c30a57f98b73\" id=\"hs-cta-f765f6a0-a051-4753-9955-c30a57f98b73\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/7137721\/f765f6a0-a051-4753-9955-c30a57f98b73\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-f765f6a0-a051-4753-9955-c30a57f98b73\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/7137721\/f765f6a0-a051-4753-9955-c30a57f98b73.png\"  alt=\"Scarica il whitepaper\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(7137721, 'f765f6a0-a051-4753-9955-c30a57f98b73', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fatturazione elettronica europea: sei pronto al cambiamento? Dal 2028 diventer\u00e0 obbligatoria in tutta l\u2019UE, con un formato standard per le operazioni intraUE. Scopri cosa significa per la tua azienda e come adeguarti! <\/p>\n","protected":false},"author":2,"featured_media":25915,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"reading_time":0,"inline_featured_image":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[41],"tags":[55,43],"class_list":["post-25862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-fatturazione-elettronica","tag-gestione-documentale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla<\/title>\n<meta name=\"description\" content=\"Tutto quel che c\u2019\u00e8 da sapere per adeguarsi all\u2019obbligo di fatturazione elettronica europea in vigore dal 2028.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla\" \/>\n<meta property=\"og:description\" content=\"Tutto quel che c\u2019\u00e8 da sapere per adeguarsi all\u2019obbligo di fatturazione elettronica europea in vigore dal 2028.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla\" \/>\n<meta property=\"og:site_name\" content=\"Top Consult\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T15:09:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T17:15:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2025\/03\/banner_evidenza_Fatturazione_elettronica_europea_perche_se_ne_parla-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Top Consult Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Top Consult Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla","description":"Tutto quel che c\u2019\u00e8 da sapere per adeguarsi all\u2019obbligo di fatturazione elettronica europea in vigore dal 2028.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla","og_locale":"it_IT","og_type":"article","og_title":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla","og_description":"Tutto quel che c\u2019\u00e8 da sapere per adeguarsi all\u2019obbligo di fatturazione elettronica europea in vigore dal 2028.","og_url":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla","og_site_name":"Top Consult","article_published_time":"2025-03-19T15:09:30+00:00","article_modified_time":"2025-03-20T17:15:10+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2025\/03\/banner_evidenza_Fatturazione_elettronica_europea_perche_se_ne_parla-1.jpg","type":"image\/jpeg"}],"author":"Top Consult Team","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Top Consult Team","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#article","isPartOf":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla"},"author":{"name":"Top Consult Team","@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/5f097e487fbfba44aba10eb3dc4be087"},"headline":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla","datePublished":"2025-03-19T15:09:30+00:00","dateModified":"2025-03-20T17:15:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla"},"wordCount":756,"image":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#primaryimage"},"thumbnailUrl":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2025\/03\/banner_evidenza_Fatturazione_elettronica_europea_perche_se_ne_parla-1.jpg","keywords":["Fatturazione Elettronica","Gestione Documentale"],"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla","url":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla","name":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla","isPartOf":{"@id":"https:\/\/www.topconsult.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#primaryimage"},"image":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#primaryimage"},"thumbnailUrl":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2025\/03\/banner_evidenza_Fatturazione_elettronica_europea_perche_se_ne_parla-1.jpg","datePublished":"2025-03-19T15:09:30+00:00","dateModified":"2025-03-20T17:15:10+00:00","author":{"@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/5f097e487fbfba44aba10eb3dc4be087"},"description":"Tutto quel che c\u2019\u00e8 da sapere per adeguarsi all\u2019obbligo di fatturazione elettronica europea in vigore dal 2028.","breadcrumb":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#primaryimage","url":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2025\/03\/banner_evidenza_Fatturazione_elettronica_europea_perche_se_ne_parla-1.jpg","contentUrl":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2025\/03\/banner_evidenza_Fatturazione_elettronica_europea_perche_se_ne_parla-1.jpg","width":640,"height":480,"caption":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla"},{"@type":"BreadcrumbList","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/fatturazione-elettronica-europea-cose-e-perche-se-ne-parla#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.topconsult.it\/it"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.topconsult.it\/it\/blog"},{"@type":"ListItem","position":3,"name":"News","item":"https:\/\/www.topconsult.it\/it\/blog\/news"},{"@type":"ListItem","position":4,"name":"Fatturazione elettronica europea: cos\u2019\u00e8 e perch\u00e9 se ne parla"}]},{"@type":"WebSite","@id":"https:\/\/www.topconsult.it\/it\/#website","url":"https:\/\/www.topconsult.it\/it\/","name":"Top Consult","description":"Avanti Veloce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.topconsult.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/5f097e487fbfba44aba10eb3dc4be087","name":"Top Consult Team","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/690874ebc6b0113812b53802a25f3717e45ed9da486ed9ec2a4620d04354039c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/690874ebc6b0113812b53802a25f3717e45ed9da486ed9ec2a4620d04354039c?s=96&d=mm&r=g","caption":"Top Consult Team"}}]}},"_links":{"self":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts\/25862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/comments?post=25862"}],"version-history":[{"count":21,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts\/25862\/revisions"}],"predecessor-version":[{"id":25937,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts\/25862\/revisions\/25937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/media\/25915"}],"wp:attachment":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/media?parent=25862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/categories?post=25862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/tags?post=25862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}