{"id":8543,"date":"2017-11-23T12:36:58","date_gmt":"2017-11-23T11:36:58","guid":{"rendered":"https:\/\/www.topconsult.it\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale\/"},"modified":"2022-12-12T19:06:36","modified_gmt":"2022-12-12T18:06:36","slug":"progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale","status":"publish","type":"post","link":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale","title":{"rendered":"Gruppo PRADA, progetto di Gestione Documentale e Conservazione Digitale"},"content":{"rendered":"<div class=\"container-fluid\">\n<div class=\"row\">\n<h4 class=\"bg-grey light spacer-in-2 spacer-in-left-2 spacer-in-right-2\">Prada &egrave; il pi&ugrave; grande gruppo italiano della moda e del lusso con un fatturato di 3,184 miliardi di euro nell&rsquo;esercizio fiscale 2016 e pi&ugrave; di 12.400 dipendenti in tutto il mondo. Opera con i propri marchi Prada, Miu Miu, Church, Car Shoe, la storica pasticceria milanese Marchesi, e su licenza anche nel settore degli occhiali e dei profumi. I prodotti, fabbricati in 13 unit&agrave; produttive, di cui 11 in Italia, o creati da fornitori esterni di alta qualit&agrave;, sono venduti in 70 paesi attraverso una rete diretta di 620 negozi e la presenza nella grande distribuzione.<\/h4>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-6 col-md-4 spacer-1\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg\" alt=\"Top Consult Finalista Digital360 Awards con il progetto realizzato per il Gruppo Prada\" width=\"961\" height=\"528\" \/><\/div>\n<div class=\"col-sm-6 col-md-8 spacer-1\">\n<p class=\"h3\">Progetto finalista<\/p>\n<p>ll Progetto Europeo del Gruppo PRADA per la realizzazione di una Piattaforma Enterprise di Gestione Documentale e Conservazione Digitale si &egrave; qualificato per la fase finale del 2017 Digital360 AWARDS.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<div class=\"col-sm-6 col-md-4 col-sm-push-6 col-md-push-8 spacer-1\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/Prada_Digital360_Awards_Gestione_Documentale_e_Conservazione_Digitale.jpg\" alt=\"progetto realizzato per il Gruppo Prada - la problematica per la gestione dei documenti e la conservazione digitale\" width=\"730\" height=\"576\" \/><\/div>\n<div class=\"col-sm-6 col-md-8 col-sm-pull-6 col-md-pull-4 spacer-1\">\n<p class=\"h3\">I numeri che fanno la differenza:<\/p>\n<p><strong>3 piattaforme documentali<\/strong> enterprise con fault tolerance e load balancing per <strong>1.200 utenti contemporanei<\/strong> che gestiscono <strong>6 archivi documentali<\/strong>, <strong>7 archivi di conservazione digitale<\/strong> a norma di legge disponibili per <strong>12 Company in Italia e Europa<\/strong>.<\/p>\n<\/div>\n<\/div>\n<hr \/>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<div class=\"col-sm-6 col-md-4 spacer-1\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/Prada_Digital360_Awards_Gestione_Documentale_Soluzioni.jpg\" alt=\"progetto realizzato per il Gruppo Prada - le soluzioni di gestione documentale e conservazione digitale\" width=\"832\" height=\"683\" \/><\/div>\n<div class=\"col-sm-6 col-md-8 spacer-1\">\n<p class=\"h3 text-pink\" style=\"text-align: left;\">La problematica:<\/p>\n<p>Il gruppo aveva l&rsquo;esigenza di costruire una gestione centralizzata e armonizzata delle proprie attivit&agrave; operative, articolate e complesse, dislocate in Italia e all&rsquo;estero, integrando la gestione elettronica dei documenti (prodotti e scambiati in volumi molto elevati) con il sistema gestionale aziendale SAP che controlla tutti gli aspetti amministrativi e contabili.<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<p>Altro obiettivo strategico era la dematerializzazione dei documenti in tutta l&rsquo;azienda, per poter lavorare senza la carta, eliminando i vecchi archivi locali e centrali e rendendo i processi lavorativi digitalizzati, cio&egrave; pi&ugrave; snelli, veloci e produttivi.<\/p>\n<p class=\"h3 text-pink\" style=\"text-align: left;\">Le soluzioni<\/p>\n<p><strong>Integrazione SAP Ciclo Attivo &#8211;&nbsp;<\/strong><strong>Integrazione SAP Ciclo&nbsp;Passivo<\/strong><\/p>\n<p><strong>Integrazione Stealth &#8211;&nbsp;<\/strong><strong>Intercompany<\/strong><\/p>\n<p><strong>Contabilit&agrave; e Finanza &#8211;&nbsp;<\/strong><strong>Digitalizzazione cartaceo<\/strong><\/p>\n<p><strong>Fascicolo del Dipendente (HR)<\/strong><\/p>\n<p style=\"text-align: center;\"><span class=\"fa-2x\"><a class=\"btn btn-primary\" href=\"\/it\/blog\/eventi\">PARTECIPA AI NOSTRI EVENTI<br class=\"visible-xs\" \/>E POTRAI ASSISTERE AD UNA<br \/>DEMO LIVE DELLE VARIE FUNZIONALITA&#8217;<\/a>&nbsp;<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<div class=\"col-sm-6 col-md-4 col-sm-push-6 col-md-push-8 spacer-1\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/Prada_Digital360_Awards_Architettura_Produzione_Finance.jpg\" alt=\"Progetto realizzato per il Gruppo Prada - architettura gestione documentale per produzione e finance\" width=\"1184\" height=\"688\" \/><\/div>\n<div class=\"col-sm-6 col-md-8 col-sm-pull-6 col-md-pull-4 spacer-1\">\n<p class=\"h3\">Finance:<\/p>\n<p><strong>Finance<\/strong>, ciclo attivo e passivo integrati con SAP ERP e STEALTH. HR, gestione del fascicolo di ogni dipendente.<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<p>E&rsquo; stata installata la piattaforma documentale enterprise TopMedia Social NED di Top Consult, basata su un&rsquo;architettura potente e robusta anche in condizioni di carico molto elevate. Dotata di alta affidabilit&agrave; con funzioni di load balancing e fault tolerance, la piattaforma &egrave; orientata allo smart working e altamente integrabile.<\/p>\n<p>Per la gestione di tutti i documenti dei flussi gestionali e contabili in Italia e in 10 paesi europei, la piattaforma documentale &egrave; integrata con il sistema gestionale SAP, via ArchiveLink, mediante il connettore &ldquo;Connect per SAP&rdquo;, appositamente progettato da Top Consult, e con altri gestionali specializzati come ad esempio Stealth.<\/p>\n<p>Viene effettuata in house la<span>&nbsp;<\/span><strong>conservazione digitale a norma di legge dei documenti fiscali<\/strong><span>&nbsp;<\/span>delle diverse aziende italiane: fatture attive e passive, scritture contabili, registri IVA, libri magazzino, ecc.. Si usa il modulo Lex di Top Consult, assieme ai servizi di<span>&nbsp;<\/span><strong>consulenza legale, organizzativa e applicativa ConLex e ManLex<\/strong>.<\/p>\n<p class=\"h3 text-pink\">Vantaggi Produzione- Finance:<strong><br \/><\/strong><\/p>\n<p><strong>Ottimizzazione delle performance sull&rsquo;ambiente di gestione; <\/strong><\/p>\n<p><strong>Maggiore scalabilit&agrave; in caso di nascita di nuovi archivi<\/strong>&nbsp;<\/p>\n<\/div>\n<\/div>\n<hr \/>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<div class=\"col-sm-6 col-md-4 spacer-1\"><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/Prada_Digital360_Awards_Architettura_Produzione_HR.jpg\" alt=\"Progetto realizzato per il Gruppo Prada - architettura gestione documentale per personale e HR\" width=\"390\" height=\"326\" \/><\/div>\n<div class=\"col-sm-6 col-md-8 spacer-1\">\n<p class=\"h3\">Personale:<\/p>\n<p>Nel settore del <strong>Personale<\/strong>, il sistema documentale &egrave; inoltre integrato con la soluzione SAP per le risorse umane e gestisce il fascicolo del dipendente (CV, lettere assunzione, contratti e lettere incarico, attribuzione device aziendali come cellulari e tablet, ecc.).<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<p>Piattaforma Documentale separata dedicata ad HR. Questa Piattaforma, sostenendo un unico archivio di gestione, potr&agrave; sostenere anche il suo archivio di conservazione senza bisogno di una piattaforma dedicata.<\/p>\n<p class=\"h3 text-pink\">Vantaggi produzione &#8211; HR:<\/p>\n<p><strong>Separare in modo esplicito l&rsquo;ambiente HR significa garantire una gestione indipendente delle installazioni (incluse le politiche di aggiornamento e di backup) e di riservatezza<\/strong><\/p>\n<\/div>\n<\/div>\n<hr \/>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<div class=\"col-sm-12\">\n<p><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"img-responsive\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/Digital360Awards_piattaforma_documentale_TopMediaSocialNED.jpg\" alt=\"Top Consult Finalista Digital360 Awards con il progetto realizzato per il Gruppo Prada\" width=\"981\" height=\"732\" \/><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm-12\">\n<p class=\"h3 text-pink\">I benefici del progetto documentale, la sparizione della carta:<\/p>\n<p>L&rsquo;impegnativo <strong>progetto<\/strong> di gestione documentale in Prada ha uno sviluppo pluriennale; iniziato nel 2015 con la migrazione delle applicazioni sulla nuova piattaforma TopMedia Social NED e la reingegnerizzazione dei processi per adeguarli ai nuovi scenari evolutivi, sar&agrave; completato nel 2018.<\/p>\n<p>Nella piattaforma sono state introdotte anche specifiche modalit&agrave; di test per le varie categorie di applicazioni, in modo da rendere pi&ugrave; semplici e veloci cambiamenti e sviluppi.<\/p>\n<p>Le capacit&agrave; di scalabilit&agrave;, robustezza e flessibilit&agrave; della piattaforma enterprise di Top Consult consentono di sostenere senza problemi ritmi e volumi di tutti i complessi ambienti applicativi di Prada. Ad esempio per le sole applicazioni amministrative e contabili in Italia e nelle consociate collegate a SAP &egrave; possibile l&rsquo;accesso di ben mille utenti contemporanei.<\/p>\n<p>La gestione documentale e le applicazioni di business, mediante il colloquio dati-documenti, sono integrate su scala internazionale. Gli utenti italiani e stranieri possono accedere in pochi secondi alle informazioni necessarie al proprio lavoro: oltre 10 milioni di documenti sono archiviati nel sistema documentale, tutti disponibili in linea.<\/p>\n<p>L&rsquo;integrazione documentale-gestionale e la progressiva digitalizzazione dei documenti rendono i processi aziendali pi&ugrave; fluidi e veloci. La carta viene eliminata in moltissimi processi e spariscono i tradizionali archivi cartacei sia negli uffici sia negli spazi centrali.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><span class=\"fa-2x\"><a class=\"btn btn-primary\" href=\"\/it\/blog\/eventi\">SCOPRI DI PIU&#8217;<br \/>PARTECIPA AI NOSTRI EVENTI GRATUITI<\/a>&nbsp;<\/span><\/p>\n<h3 class=\"bg-grey light spacer-in-2 spacer-in-left-2 spacer-in-right-2 bold\" style=\"text-align: center;\"><strong>Elementi distintivi e di reale innovativit&agrave;\/originalit&agrave; della soluzione: <\/strong><\/h3>\n<h3 class=\"bg-grey light spacer-in-2 spacer-in-left-2 spacer-in-right-2 h4\" style=\"text-align: center;\">TopMedia Social NED per la gestione documentale e la collaborazione aziendale &egrave; una piattaforma di concezione completamente nuova. Affidabile e scalabile, &egrave; la prima piattaforma documentale italiana di tipo enterprise, equivalente a quelle dei leader mondiali del settore, ma conforme alle leggi italiane, meno complessa e meno costosa. Ha un&rsquo;interfaccia utente intuitiva, dotata di funzioni social mutuate da smartphone e social network fruibili su tutti i client, che estende l&rsquo;uso della gestione documentale anche a manager e mobile worker.<\/p>\n<p>L&rsquo;integrazione con SAP &egrave; realizzata mediante l&rsquo;apposito &ldquo;Connettore per SAP&rdquo; di Top Consult. Tutti i documenti generati da SAP o in ingresso a SAP vengono archiviati nella piattaforma documentale e possono essere consultati direttamente, assieme alle loro correlazioni, dagli utenti SAP e non SAP. <\/p>\n<p>La conservazione digitale dei documenti utilizza il modulo e i servizi specializzati ideati da Top Consult, pioniere della materia, creatore nel &rsquo;99 per il Comune di Pesaro del primo esempio in Italia di archivio digitale a norma di legge.<\/h3>\n<hr \/>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<p style=\"text-align: center;\"><a class=\"btn btn-lg btn-primary bold\" href=\"\/it\/blog\/news\/finalisti-con-il-progetto-del-gruppo-prada-piattaforma-documentale-integrata\">Videointervista a Pier Luigi Zaffagnini, CEO Top Consult<\/a><\/p>\n<\/div>\n<\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>3 piattaforme documentali enterprise per 1.200 utenti contemporanei che gestiscono 6 archivi documentali, 7 archivi di conservazione digitale disponibili per 12 Company.<\/p>\n","protected":false},"author":4,"featured_media":4245,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"reading_time":0,"inline_featured_image":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[41],"tags":[74,77,58,69,95,84,89,43,70,60],"class_list":["post-8543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-archiviazione-digitale","tag-case-history","tag-conservazione-digitale","tag-dematerializzazione","tag-dicono-di-noi","tag-digital-transformation","tag-document-management","tag-gestione-documentale","tag-piattaforma-documentale-enterprise","tag-topmedia-social-ned"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scopri il progetto Europeo del Gruppo PRADA di Gestione Documentale e Conservazione Digitale<\/title>\n<meta name=\"description\" content=\"3 piattaforme documentali enterprise con fault tolerance e load balancing per 1.200 utenti contemporanei che gestiscono 6 archivi documentali, 7 archivi di conservazione digitale disponibili per 12 Company in Italia e Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scopri il progetto Europeo del Gruppo PRADA di Gestione Documentale e Conservazione Digitale\" \/>\n<meta property=\"og:description\" content=\"3 piattaforme documentali enterprise con fault tolerance e load balancing per 1.200 utenti contemporanei che gestiscono 6 archivi documentali, 7 archivi di conservazione digitale disponibili per 12 Company in Italia e Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale\" \/>\n<meta property=\"og:site_name\" content=\"Top Consult\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-23T11:36:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-12T18:06:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"961\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"api user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"api user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scopri il progetto Europeo del Gruppo PRADA di Gestione Documentale e Conservazione Digitale","description":"3 piattaforme documentali enterprise con fault tolerance e load balancing per 1.200 utenti contemporanei che gestiscono 6 archivi documentali, 7 archivi di conservazione digitale disponibili per 12 Company in Italia e Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale","og_locale":"it_IT","og_type":"article","og_title":"Scopri il progetto Europeo del Gruppo PRADA di Gestione Documentale e Conservazione Digitale","og_description":"3 piattaforme documentali enterprise con fault tolerance e load balancing per 1.200 utenti contemporanei che gestiscono 6 archivi documentali, 7 archivi di conservazione digitale disponibili per 12 Company in Italia e Europa.","og_url":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale","og_site_name":"Top Consult","article_published_time":"2017-11-23T11:36:58+00:00","article_modified_time":"2022-12-12T18:06:36+00:00","og_image":[{"width":961,"height":528,"url":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg","type":"image\/jpeg"}],"author":"api user","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"api user","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#article","isPartOf":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale"},"author":{"name":"api user","@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/b924f4f9fa5ddd6e06cecdc35c8ccac6"},"headline":"Gruppo PRADA, progetto di Gestione Documentale e Conservazione Digitale","datePublished":"2017-11-23T11:36:58+00:00","dateModified":"2022-12-12T18:06:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale"},"wordCount":1028,"image":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#primaryimage"},"thumbnailUrl":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg","keywords":["Archiviazione Digitale","Case History","Conservazione Digitale","Dematerializzazione","Dicono di noi","Digital Transformation","Document Management System","Gestione Documentale","Piattaforma Documentale Enterprise","TopMedia Social NED"],"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale","url":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale","name":"Scopri il progetto Europeo del Gruppo PRADA di Gestione Documentale e Conservazione Digitale","isPartOf":{"@id":"https:\/\/www.topconsult.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#primaryimage"},"image":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#primaryimage"},"thumbnailUrl":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg","datePublished":"2017-11-23T11:36:58+00:00","dateModified":"2022-12-12T18:06:36+00:00","author":{"@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/b924f4f9fa5ddd6e06cecdc35c8ccac6"},"description":"3 piattaforme documentali enterprise con fault tolerance e load balancing per 1.200 utenti contemporanei che gestiscono 6 archivi documentali, 7 archivi di conservazione digitale disponibili per 12 Company in Italia e Europa.","breadcrumb":{"@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#primaryimage","url":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg","contentUrl":"https:\/\/www.topconsult.it\/wp-content\/uploads\/2022\/11\/progetto_Prada_Digital360Awards_Piattaforma_Documentale_Enterprise.jpg","width":961,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/www.topconsult.it\/it\/blog\/news\/progetto-europeo-del-gruppo-prada-di-gestione-documentale-e-conservazione-digitale#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.topconsult.it\/it"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.topconsult.it\/it\/blog"},{"@type":"ListItem","position":3,"name":"News","item":"https:\/\/www.topconsult.it\/it\/blog\/news"},{"@type":"ListItem","position":4,"name":"Gruppo PRADA, progetto di Gestione Documentale e Conservazione Digitale"}]},{"@type":"WebSite","@id":"https:\/\/www.topconsult.it\/it\/#website","url":"https:\/\/www.topconsult.it\/it\/","name":"Top Consult","description":"Avanti Veloce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.topconsult.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/b924f4f9fa5ddd6e06cecdc35c8ccac6","name":"api user","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.topconsult.it\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b499d7680db9c4e07bea1a162d6065176f9e42b4f428e9354656e0dd68ef052c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b499d7680db9c4e07bea1a162d6065176f9e42b4f428e9354656e0dd68ef052c?s=96&d=mm&r=g","caption":"api user"}}]}},"_links":{"self":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts\/8543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/comments?post=8543"}],"version-history":[{"count":1,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts\/8543\/revisions"}],"predecessor-version":[{"id":9067,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts\/8543\/revisions\/9067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/media\/4245"}],"wp:attachment":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/media?parent=8543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/categories?post=8543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/tags?post=8543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}