{"id":65,"count":1,"description":"Le nuove <strong>Regole Tecniche della Conservazione Digitale<\/strong> attuative del CAD-Codice dell&rsquo;amministrazione digitale (articolo 44) diventate obbligatorie dal marzo 2017 hanno reso superata la delibera Cnipa 11\/2004 e la dicitura &ldquo;conservazione sostitutiva&rdquo; sino ad allora utilizzata, la definizione di conservazione digitale fa riferimento a tutte le attivit&agrave; svolte per salvaguardare e custodire nel tempo gli archivi di documenti e dati senza ricorrere in alcun modo alla carta.\r\nLa normativa richiede che tale protezione sia garantita nel lungo periodo e che si abbia la sicurezza di poter recuperare le informazioni con facilit&agrave; e nella identica modalit&agrave; in cui sono state prodotte.","link":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale","name":"Regole Tecniche della Conservazione Digitale","slug":"regole-tecniche-della-conservazione-digitale","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regole Tecniche della Conservazione Digitale<\/title>\n<meta name=\"description\" content=\"Le nuove Regole Tecniche della Conservazione Digitale attuative del CAD-Codice dell\u2019amministrazione digitale (articolo 44) diventate obbligatorie dal marzo 2017 hanno reso superata la delibera Cnipa 11\/2004 e la dicitura \u201cconservazione sostitutiva\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regole Tecniche della Conservazione Digitale\" \/>\n<meta property=\"og:description\" content=\"Le nuove Regole Tecniche della Conservazione Digitale attuative del CAD-Codice dell\u2019amministrazione digitale (articolo 44) diventate obbligatorie dal marzo 2017 hanno reso superata la delibera Cnipa 11\/2004 e la dicitura \u201cconservazione sostitutiva\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale\" \/>\n<meta property=\"og:site_name\" content=\"Top Consult\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regole Tecniche della Conservazione Digitale","description":"Le nuove Regole Tecniche della Conservazione Digitale attuative del CAD-Codice dell\u2019amministrazione digitale (articolo 44) diventate obbligatorie dal marzo 2017 hanno reso superata la delibera Cnipa 11\/2004 e la dicitura \u201cconservazione sostitutiva\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale","og_locale":"it_IT","og_type":"article","og_title":"Regole Tecniche della Conservazione Digitale","og_description":"Le nuove Regole Tecniche della Conservazione Digitale attuative del CAD-Codice dell\u2019amministrazione digitale (articolo 44) diventate obbligatorie dal marzo 2017 hanno reso superata la delibera Cnipa 11\/2004 e la dicitura \u201cconservazione sostitutiva\u201d","og_url":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale","og_site_name":"Top Consult","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale","url":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale","name":"Regole Tecniche della Conservazione Digitale","isPartOf":{"@id":"https:\/\/www.topconsult.it\/it\/#website"},"description":"Le nuove Regole Tecniche della Conservazione Digitale attuative del CAD-Codice dell\u2019amministrazione digitale (articolo 44) diventate obbligatorie dal marzo 2017 hanno reso superata la delibera Cnipa 11\/2004 e la dicitura \u201cconservazione sostitutiva\u201d","breadcrumb":{"@id":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.topconsult.it\/it\/tag\/regole-tecniche-della-conservazione-digitale#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.topconsult.it\/it"},{"@type":"ListItem","position":2,"name":"Regole Tecniche della Conservazione Digitale"}]},{"@type":"WebSite","@id":"https:\/\/www.topconsult.it\/it\/#website","url":"https:\/\/www.topconsult.it\/it\/","name":"Top Consult","description":"Avanti Veloce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.topconsult.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/tags\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.topconsult.it\/it\/wp-json\/wp\/v2\/posts?tags=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}